{"id":89621,"date":"2024-11-30T05:12:30","date_gmt":"2024-11-30T05:12:30","guid":{"rendered":"https:\/\/realpornblogger.com\/index.php\/2024\/11\/30\/indoor-sun-bathing\/"},"modified":"2024-11-30T05:12:30","modified_gmt":"2024-11-30T05:12:30","slug":"indoor-sun-bathing","status":"publish","type":"post","link":"https:\/\/realpornblogger.com\/index.php\/2024\/11\/30\/indoor-sun-bathing\/","title":{"rendered":"Indoor Sun Bathing"},"content":{"rendered":"<h2 class='wp-block-heading'>Indoor Sun Bathing<\/h2>\n\n                \n                <script src=\"https:\/\/cdn.fluidplayer.com\/v3\/current\/fluidplayer.min.js\"><\/script>\n                <video id=\"video-id\"><source src=\"https:\/\/c75f0e208f.mjedge.net\/6\/4\/1\/d\/c\/641dcaf7cf98d\/NM0063_eroticmedusa_indoorsunbathing_promomusic_trailer.mp4\" type=\"video\/mp4\" \/><\/video>\n                <script>\n                    var myFP = fluidPlayer(\n                        'video-id', {\n                        \"layoutControls\": {\n                            \"controlBar\": {\n                                \"autoHideTimeout\": 3,\n                                \"animated\": true,\n                                \"autoHide\": true\n                            },\n                            \"htmlOnPauseBlock\": {\n                                \"html\": null,\n                                \"height\": null,\n                                \"width\": null\n                            },\n                            \"autoPlay\": false,\n                            \"mute\": false,\n                            \"allowTheatre\": true,\n                            \"playPauseAnimation\": false,\n                            \"playbackRateEnabled\": false,\n                            \"allowDownload\": false,\n                            \"playButtonShowing\": true,\n                            \"fillToContainer\": true,\n                            \"posterImage\": \"\"\n                        },\n                        \"vastOptions\": {\n                            \"adList\": [\n                                {\n                                    \"roll\": \"preRoll\",\n                                    \"vastTag\": \"https:\/\/go.bbrdbr.com\/api\/models\/vast?campaignId=afm&sourceId=rpb&action=signUpModalDirectLinkInteractive&userId=985197bd1f225ab80de07604735c3c170b654764be81d82b2e36b00b1204dd94\",\n                                    \"adText\": \"\"\n                                },\n                                {\n                                    \"roll\": \"midRoll\",\n                                    \"vastTag\": \"https:\/\/go.bbrdbr.com\/api\/models\/vast?campaignId=afm&sourceId=rpb&action=signUpModalDirectLinkInteractive&userId=985197bd1f225ab80de07604735c3c170b654764be81d82b2e36b00b1204dd94\",\n                                    \"adText\": \"\"\n                                },\n                                {\n                                    \"roll\": \"postRoll\",\n                                    \"vastTag\": \"https:\/\/go.bbrdbr.com\/api\/models\/vast?campaignId=afm&sourceId=rpb&action=signUpModalDirectLinkInteractive&userId=985197bd1f225ab80de07604735c3c170b654764be81d82b2e36b00b1204dd94\",\n                                    \"adText\": \"\"\n                                }\n                            ],\n                            \"adCTAText\": false,\n                            \"adCTATextPosition\": \"\"\n                        }\n                    });\n                <\/script>\n                \n            \n            <div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n            \n            <div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/realpornblogger.com\">Home<\/a><\/div>\n            \n            \n            <div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/register.nickmarxx.com\/track\/DimitarAFM.3.114.286.0.0.0.0.0\" target=\"_blank\" rel=\"noreferrer noopener\">Watch full video<\/a><\/div>\n            \n            <\/div>","protected":false},"excerpt":{"rendered":"<p>Indoor Sun Bathing<\/p>\n","protected":false},"author":1,"featured_media":89620,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[55],"tags":[3193,2718],"class_list":["post-89621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-new-videos","tag-erotic-medusa","tag-nickmarxx"],"_links":{"self":[{"href":"https:\/\/realpornblogger.com\/index.php\/wp-json\/wp\/v2\/posts\/89621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/realpornblogger.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/realpornblogger.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/realpornblogger.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/realpornblogger.com\/index.php\/wp-json\/wp\/v2\/comments?post=89621"}],"version-history":[{"count":0,"href":"https:\/\/realpornblogger.com\/index.php\/wp-json\/wp\/v2\/posts\/89621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/realpornblogger.com\/index.php\/wp-json\/wp\/v2\/media\/89620"}],"wp:attachment":[{"href":"https:\/\/realpornblogger.com\/index.php\/wp-json\/wp\/v2\/media?parent=89621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/realpornblogger.com\/index.php\/wp-json\/wp\/v2\/categories?post=89621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/realpornblogger.com\/index.php\/wp-json\/wp\/v2\/tags?post=89621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}